{"id":25570,"date":"2022-02-18T13:33:57","date_gmt":"2022-02-18T21:33:57","guid":{"rendered":"https:\/\/www.camarenahealth.org\/events\/unidad-sanitaria-movil-de-mariposa-2\/"},"modified":"2022-02-18T13:33:57","modified_gmt":"2022-02-18T21:33:57","slug":"unidad-sanitaria-movil-de-mariposa-2","status":"publish","type":"mec-events","link":"https:\/\/www.camarenahealth.org\/es\/events\/unidad-sanitaria-movil-de-mariposa-2\/","title":{"rendered":"Unidad sanitaria m\u00f3vil de Mariposa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":104,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","tags":[],"mec_category":[270],"class_list":["post-25570","mec-events","type-mec-events","status-publish","hentry","mec_category-unidad-sanitaria-movil-de-mariposa","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unidad sanitaria m\u00f3vil de Mariposa - Camarena Health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.camarenahealth.org\/es\/events\/unidad-sanitaria-movil-de-mariposa-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unidad sanitaria m\u00f3vil de Mariposa - Camarena Health\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.camarenahealth.org\/es\/events\/unidad-sanitaria-movil-de-mariposa-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Camarena Health\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/events\\\/unidad-sanitaria-movil-de-mariposa-2\\\/\",\"url\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/events\\\/unidad-sanitaria-movil-de-mariposa-2\\\/\",\"name\":\"Unidad sanitaria m\u00f3vil de Mariposa - Camarena Health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/#website\"},\"datePublished\":\"2022-02-18T21:33:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/events\\\/unidad-sanitaria-movil-de-mariposa-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/events\\\/unidad-sanitaria-movil-de-mariposa-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/events\\\/unidad-sanitaria-movil-de-mariposa-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/salud-camarena\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unidad sanitaria m\u00f3vil de Mariposa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/\",\"name\":\"Camarena Health\",\"description\":\"We Are Community. We Are Family. We Are Health.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/#organization\",\"name\":\"Camarena Health\",\"url\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.camarenahealth.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Camarena-Health_2022-Logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.camarenahealth.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Camarena-Health_2022-Logo.svg\",\"width\":1920,\"height\":382,\"caption\":\"Camarena Health\"},\"image\":{\"@id\":\"https:\\\/\\\/www.camarenahealth.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unidad sanitaria m\u00f3vil de Mariposa - Camarena Health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.camarenahealth.org\/es\/events\/unidad-sanitaria-movil-de-mariposa-2\/","og_locale":"es_ES","og_type":"article","og_title":"Unidad sanitaria m\u00f3vil de Mariposa - Camarena Health","og_url":"https:\/\/www.camarenahealth.org\/es\/events\/unidad-sanitaria-movil-de-mariposa-2\/","og_site_name":"Camarena Health","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.camarenahealth.org\/es\/events\/unidad-sanitaria-movil-de-mariposa-2\/","url":"https:\/\/www.camarenahealth.org\/es\/events\/unidad-sanitaria-movil-de-mariposa-2\/","name":"Unidad sanitaria m\u00f3vil de Mariposa - Camarena Health","isPartOf":{"@id":"https:\/\/www.camarenahealth.org\/es\/#website"},"datePublished":"2022-02-18T21:33:57+00:00","breadcrumb":{"@id":"https:\/\/www.camarenahealth.org\/es\/events\/unidad-sanitaria-movil-de-mariposa-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.camarenahealth.org\/es\/events\/unidad-sanitaria-movil-de-mariposa-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.camarenahealth.org\/es\/events\/unidad-sanitaria-movil-de-mariposa-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.camarenahealth.org\/es\/salud-camarena\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/www.camarenahealth.org\/es\/events\/"},{"@type":"ListItem","position":3,"name":"Unidad sanitaria m\u00f3vil de Mariposa"}]},{"@type":"WebSite","@id":"https:\/\/www.camarenahealth.org\/es\/#website","url":"https:\/\/www.camarenahealth.org\/es\/","name":"Camarena Health","description":"We Are Community. We Are Family. We Are Health.","publisher":{"@id":"https:\/\/www.camarenahealth.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.camarenahealth.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.camarenahealth.org\/es\/#organization","name":"Camarena Health","url":"https:\/\/www.camarenahealth.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.camarenahealth.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.camarenahealth.org\/wp-content\/uploads\/2021\/12\/Camarena-Health_2022-Logo.svg","contentUrl":"https:\/\/www.camarenahealth.org\/wp-content\/uploads\/2021\/12\/Camarena-Health_2022-Logo.svg","width":1920,"height":382,"caption":"Camarena Health"},"image":{"@id":"https:\/\/www.camarenahealth.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.camarenahealth.org\/es\/wp-json\/wp\/v2\/mec-events\/25570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camarenahealth.org\/es\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.camarenahealth.org\/es\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.camarenahealth.org\/es\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camarenahealth.org\/es\/wp-json\/wp\/v2\/comments?post=25570"}],"version-history":[{"count":0,"href":"https:\/\/www.camarenahealth.org\/es\/wp-json\/wp\/v2\/mec-events\/25570\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.camarenahealth.org\/es\/wp-json\/wp\/v2\/media?parent=25570"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camarenahealth.org\/es\/wp-json\/wp\/v2\/tags?post=25570"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.camarenahealth.org\/es\/wp-json\/wp\/v2\/mec_category?post=25570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}